{"id":12888,"date":"2016-08-29T12:13:58","date_gmt":"2016-08-29T10:13:58","guid":{"rendered":"http:\/\/dentalesparreguera.com\/?p=12888\/"},"modified":"2017-07-23T12:46:37","modified_gmt":"2017-07-23T10:46:37","slug":"plasma-ric-plaquetes-efecte-els-teixits-dentals","status":"publish","type":"post","link":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/","title":{"rendered":"Plasma ric en plaquetes, efecte en els teixits dentals."},"content":{"rendered":"<p>Una de les finalitats de la ter\u00e0pia periodontal \u00e9s la regeneraci\u00f3 dels teixits periodontals. Aquests processos s\u00f3n mitjans per l&#8217;acci\u00f3 dels factors de creixement (FC) que regulen la proliferaci\u00f3, diferenciaci\u00f3, quimiotaxia i s\u00edntesi de la matriu extracel\u00b7lular.<\/p>\n<p>Generalment, els estudis que investiguen l&#8217;\u00fas de plasma ric en plaquetes en el tractament dels defectes intraossis han llan\u00e7at resultats mixtos.<\/p>\n<p>Els investigadors de l&#8217;Oral Medicine Clinical Center, a l&#8217;Hospital of Xinjiang Medical University a la Xina, van avaluar l&#8217;efic\u00e0cia de PRP, comparant el nivell d&#8217;inserci\u00f3 cl\u00ednica i la profunditat de la borsa en els pacients que van rebre PRP com un complement a la ter\u00e0pia periodontal, ja que presentaven un defecte intraossi i comparant-los amb els pacients que no el van rebre. A m\u00e9s, es va analitzar la influ\u00e8ncia de la Regeneraci\u00f3 Tissular Guiada i diferents dissenys d&#8217;estudi, en els resultats cl\u00ednics dels defectes intraossis.<\/p>\n<p>Per a aix\u00f2 es va realitzar una revisi\u00f3 sistem\u00e0tica d&#8217;articles publicats des de Juny del 2015 fins a l&#8217;actualitat. Combinant les dades dels assaigs aleatoris per avaluar els resultats cl\u00ednics mitjan\u00e7ant un model d&#8217;efectes aleatoris.<\/p>\n<p>Dels 307 estudis analitzats, els resultats van demostrar que un augment en el nivell d&#8217;inserci\u00f3 i una disminuci\u00f3 en la profunditat de les bosses periodontals, va ser observat en els subjectes que van rebre PRP com un complement a la ter\u00e0pia periodontal en comparaci\u00f3 amb els subjectes que no ho van fer.<\/p>\n<p>En conclusi\u00f3 l&#8217;\u00fas complementari de Plasma Ric en Plaquetes juntament amb procediments d&#8217;empelt convencionals pot ser un tractament benefici\u00f3s. No obstant aix\u00f2, quan es combina amb l&#8217;\u00fas d&#8217;una t\u00e8cnica de regeneraci\u00f3, com Regeneraci\u00f3 Tissular Guiada, l&#8217;efecte benefici\u00f3s del PRP en el tractament de defectes intraossis \u00e9s insignificant.<\/p>\n<p>ARTICLE COMPLET I FONT:<\/p>\n<blockquote data-secret=\"IVahaB5yGD\" class=\"wp-embedded-content\"><p><a href=\"https:\/\/www.gacetadental.com\/2011\/09\/plasma-rico-en-plaquetas-en-la-clnica-dental-25816\/\">Plasma rico en plaquetas en la cl&#237;nica dental<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.gacetadental.com\/2011\/09\/plasma-rico-en-plaquetas-en-la-clnica-dental-25816\/embed\/#?secret=IVahaB5yGD\" data-secret=\"IVahaB5yGD\" width=\"600\" height=\"338\" title=\"&#8220;Plasma rico en plaquetas en la cl&#237;nica dental&#8221; &#8212; Gaceta Dental\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de les finalitats de la ter\u00e0pia periodontal \u00e9s la regeneraci\u00f3 dels teixits periodontals. Aquests processos s\u00f3n mitjans per l&#8217;acci\u00f3 dels factors de creixement (FC) que regulen la proliferaci\u00f3, diferenciaci\u00f3, quimiotaxia i s\u00edntesi de la matriu extracel\u00b7lular. Generalment, els estudis que investiguen l&#8217;\u00fas de plasma ric en plaquetes en el tractament dels defectes intraossis han [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12202,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[30],"tags":[59],"class_list":["post-12888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mima-2","tag-curiositats"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plasma ric en plaquetes, efecte en els teixits dentals. - Mima Cl\u00ednica Dental<\/title>\n<meta name=\"description\" content=\"Generalment, els estudis que investiguen l&#039;\u00fas de plasma ric en plaquetes en el tractament dels defectes intraossis han llan\u00e7at resultats mixtos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plasma ric en plaquetes, efecte en els teixits dentals. - Mima Cl\u00ednica Dental\" \/>\n<meta property=\"og:description\" content=\"Generalment, els estudis que investiguen l&#039;\u00fas de plasma ric en plaquetes en el tractament dels defectes intraossis han llan\u00e7at resultats mixtos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/\" \/>\n<meta property=\"og:site_name\" content=\"Mima Cl\u00ednica Dental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dentalesparreguera\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-29T10:13:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-23T10:46:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dentalesparreguera.com\/wp-content\/uploads\/2016\/08\/blood-1328607_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"925\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mireya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mireya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/\"},\"author\":{\"name\":\"Mireya\",\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/#\\\/schema\\\/person\\\/489bdb42573d20a51c32a0563349e311\"},\"headline\":\"Plasma ric en plaquetes, efecte en els teixits dentals.\",\"datePublished\":\"2016-08-29T10:13:58+00:00\",\"dateModified\":\"2017-07-23T10:46:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/\"},\"wordCount\":328,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dentalesparreguera.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/blood-1328607_1280.jpg\",\"keywords\":[\"curiositats\"],\"articleSection\":[\"Mima\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/\",\"url\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/\",\"name\":\"Plasma ric en plaquetes, efecte en els teixits dentals. - Mima Cl\u00ednica Dental\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dentalesparreguera.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/blood-1328607_1280.jpg\",\"datePublished\":\"2016-08-29T10:13:58+00:00\",\"dateModified\":\"2017-07-23T10:46:37+00:00\",\"description\":\"Generalment, els estudis que investiguen l'\u00fas de plasma ric en plaquetes en el tractament dels defectes intraossis han llan\u00e7at resultats mixtos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dentalesparreguera.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/blood-1328607_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/dentalesparreguera.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/blood-1328607_1280.jpg\",\"width\":1280,\"height\":925,\"caption\":\"Plaquetas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/plasma-ric-plaquetes-efecte-els-teixits-dentals\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plasma ric en plaquetes, efecte en els teixits dentals.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/\",\"name\":\"Mima Cl\u00ednica Dental\",\"description\":\"Tu Cl\u00ednica Dental de confianza en Esparreguera\",\"publisher\":{\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/#organization\",\"name\":\"Mima Cl\u00ednica Dental\",\"url\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dentalesparreguera.com\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/LOGOS-blog-mimaMIMA-2-150ppp.png\",\"contentUrl\":\"https:\\\/\\\/dentalesparreguera.com\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/LOGOS-blog-mimaMIMA-2-150ppp.png\",\"width\":849,\"height\":403,\"caption\":\"Mima Cl\u00ednica Dental\"},\"image\":{\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dentalesparreguera\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dentalesparreguera.com\\\/ca\\\/#\\\/schema\\\/person\\\/489bdb42573d20a51c32a0563349e311\",\"name\":\"Mireya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe707002a8b7fe472c62addedc7f74a06e155ecf48b12b563b52d2021b7e87b3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe707002a8b7fe472c62addedc7f74a06e155ecf48b12b563b52d2021b7e87b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe707002a8b7fe472c62addedc7f74a06e155ecf48b12b563b52d2021b7e87b3?s=96&d=mm&r=g\",\"caption\":\"Mireya\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plasma ric en plaquetes, efecte en els teixits dentals. - Mima Cl\u00ednica Dental","description":"Generalment, els estudis que investiguen l'\u00fas de plasma ric en plaquetes en el tractament dels defectes intraossis han llan\u00e7at resultats mixtos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/","og_locale":"ca_ES","og_type":"article","og_title":"Plasma ric en plaquetes, efecte en els teixits dentals. - Mima Cl\u00ednica Dental","og_description":"Generalment, els estudis que investiguen l'\u00fas de plasma ric en plaquetes en el tractament dels defectes intraossis han llan\u00e7at resultats mixtos.","og_url":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/","og_site_name":"Mima Cl\u00ednica Dental","article_publisher":"https:\/\/www.facebook.com\/dentalesparreguera\/","article_published_time":"2016-08-29T10:13:58+00:00","article_modified_time":"2017-07-23T10:46:37+00:00","og_image":[{"width":1280,"height":925,"url":"https:\/\/dentalesparreguera.com\/wp-content\/uploads\/2016\/08\/blood-1328607_1280.jpg","type":"image\/jpeg"}],"author":"Mireya","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Mireya","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/#article","isPartOf":{"@id":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/"},"author":{"name":"Mireya","@id":"https:\/\/dentalesparreguera.com\/ca\/#\/schema\/person\/489bdb42573d20a51c32a0563349e311"},"headline":"Plasma ric en plaquetes, efecte en els teixits dentals.","datePublished":"2016-08-29T10:13:58+00:00","dateModified":"2017-07-23T10:46:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/"},"wordCount":328,"commentCount":0,"publisher":{"@id":"https:\/\/dentalesparreguera.com\/ca\/#organization"},"image":{"@id":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/#primaryimage"},"thumbnailUrl":"https:\/\/dentalesparreguera.com\/wp-content\/uploads\/2016\/08\/blood-1328607_1280.jpg","keywords":["curiositats"],"articleSection":["Mima"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/","url":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/","name":"Plasma ric en plaquetes, efecte en els teixits dentals. - Mima Cl\u00ednica Dental","isPartOf":{"@id":"https:\/\/dentalesparreguera.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/#primaryimage"},"image":{"@id":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/#primaryimage"},"thumbnailUrl":"https:\/\/dentalesparreguera.com\/wp-content\/uploads\/2016\/08\/blood-1328607_1280.jpg","datePublished":"2016-08-29T10:13:58+00:00","dateModified":"2017-07-23T10:46:37+00:00","description":"Generalment, els estudis que investiguen l'\u00fas de plasma ric en plaquetes en el tractament dels defectes intraossis han llan\u00e7at resultats mixtos.","breadcrumb":{"@id":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/#primaryimage","url":"https:\/\/dentalesparreguera.com\/wp-content\/uploads\/2016\/08\/blood-1328607_1280.jpg","contentUrl":"https:\/\/dentalesparreguera.com\/wp-content\/uploads\/2016\/08\/blood-1328607_1280.jpg","width":1280,"height":925,"caption":"Plaquetas"},{"@type":"BreadcrumbList","@id":"https:\/\/dentalesparreguera.com\/ca\/plasma-ric-plaquetes-efecte-els-teixits-dentals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dentalesparreguera.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Plasma ric en plaquetes, efecte en els teixits dentals."}]},{"@type":"WebSite","@id":"https:\/\/dentalesparreguera.com\/ca\/#website","url":"https:\/\/dentalesparreguera.com\/ca\/","name":"Mima Cl\u00ednica Dental","description":"Tu Cl\u00ednica Dental de confianza en Esparreguera","publisher":{"@id":"https:\/\/dentalesparreguera.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dentalesparreguera.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/dentalesparreguera.com\/ca\/#organization","name":"Mima Cl\u00ednica Dental","url":"https:\/\/dentalesparreguera.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/dentalesparreguera.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/dentalesparreguera.com\/wp-content\/uploads\/2015\/08\/LOGOS-blog-mimaMIMA-2-150ppp.png","contentUrl":"https:\/\/dentalesparreguera.com\/wp-content\/uploads\/2015\/08\/LOGOS-blog-mimaMIMA-2-150ppp.png","width":849,"height":403,"caption":"Mima Cl\u00ednica Dental"},"image":{"@id":"https:\/\/dentalesparreguera.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dentalesparreguera\/"]},{"@type":"Person","@id":"https:\/\/dentalesparreguera.com\/ca\/#\/schema\/person\/489bdb42573d20a51c32a0563349e311","name":"Mireya","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/fe707002a8b7fe472c62addedc7f74a06e155ecf48b12b563b52d2021b7e87b3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe707002a8b7fe472c62addedc7f74a06e155ecf48b12b563b52d2021b7e87b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe707002a8b7fe472c62addedc7f74a06e155ecf48b12b563b52d2021b7e87b3?s=96&d=mm&r=g","caption":"Mireya"}}]}},"_links":{"self":[{"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/posts\/12888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/comments?post=12888"}],"version-history":[{"count":1,"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/posts\/12888\/revisions"}],"predecessor-version":[{"id":12890,"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/posts\/12888\/revisions\/12890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/media\/12202"}],"wp:attachment":[{"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/media?parent=12888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/categories?post=12888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dentalesparreguera.com\/ca\/wp-json\/wp\/v2\/tags?post=12888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}